{"id":2480,"date":"2021-08-28T12:15:16","date_gmt":"2021-08-28T10:15:16","guid":{"rendered":"https:\/\/www.claudioamorese.it\/?p=2480"},"modified":"2025-12-11T21:36:11","modified_gmt":"2025-12-11T20:36:11","slug":"aeolian-sailing-filicudi-6a-tappa","status":"publish","type":"post","link":"https:\/\/www.claudioamorese.it\/en\/aeolian-sailing-filicudi-6a-tappa\/","title":{"rendered":"Aeolian Sailing - Filicudi (sixth leg)"},"content":{"rendered":"\n<p><strong>La sesta tappa: Filicudi<\/strong><\/p>\n\n\n\n<p>Lentamente ci spostiamo verso Ovest per ridurre il tratto finale di ritorno a Termini Imerese. Giriamo intorno a Strombolicchio prima di fare rotta verso Filicudi<\/p>\n<p class=\"aligncenter\">\n<img decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/www.claudioamorese.it\/wp-content\/uploads\/2021\/08\/Immagine-2021-08-28-112720-e1630142956988-300x132.png\" \/><\/p>\n<p>Strombolicchio \u00e8 un neck, ossia una spina vulcanica, costituita dal magma solidificato di un vulcano di 200.000 anni fa ormai non pi\u00f9 esistente.<\/p>\n<!-- Terzo slider -->\n\n\t\t\t<!-- START Strombolicchio REVOLUTION SLIDER 6.5.5 --><p class=\"rs-p-wp-fix\"><\/p>\n\t\t\t<rs-module-wrap id=\"rev_slider_15_1_wrapper\" data-source=\"gallery\" style=\"visibility:hidden;background:transparent;padding:0;margin:0px auto;margin-top:0;margin-bottom:0;\">\n\t\t\t\t<rs-module id=\"rev_slider_15_1\" style=\"\" data-version=\"6.5.5\">\n\t\t\t\t\t<rs-slides>\n\t\t\t\t\t\t<rs-slide style=\"position: absolute;\" data-key=\"rs-73\" data-title=\"Slide\" data-duration=\"1500ms\" data-anim=\"ms:400;\" data-in=\"o:0;\" data-out=\"a:false;\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"\/\/www.claudioamorese.it\/wp-content\/plugins\/revslider\/public\/assets\/assets\/dummy.png\" alt=\"Slide\" title=\"Aeolian Sailing &#8211; Filicudi (sesta tappa)\" class=\"rev-slidebg tp-rs-img rs-lazyload\" data-lazyload=\"\/\/www.claudioamorese.it\/wp-content\/plugins\/revslider\/public\/assets\/assets\/transparent.png\" data-no-retina>\n<!--\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-15-slide-73-layer-8\" \n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:200px;y:-112px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:500px;h:375px;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:9;\"\n\t\t\t\t\t\t\t><img loading=\"lazy\" decoding=\"async\" src=\"\/\/www.claudioamorese.it\/wp-content\/plugins\/revslider\/public\/assets\/assets\/dummy.png\" class=\"tp-rs-img rs-lazyload\" width=\"2560\" height=\"1920\" data-lazyload=\"\/\/www.claudioamorese.it\/wp-content\/uploads\/2021\/08\/IMG_4594-scaled.jpg\" data-no-retina> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n-->\t\t\t\t\t\t<\/rs-slide>\n\t\t\t\t\t\t<rs-slide style=\"position: absolute;\" data-key=\"rs-74\" data-title=\"Slide\" data-duration=\"1500ms\" data-anim=\"ms:300;\" data-in=\"o:0;\" data-out=\"a:false;\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"\/\/www.claudioamorese.it\/wp-content\/plugins\/revslider\/public\/assets\/assets\/dummy.png\" alt=\"Slide\" title=\"Aeolian Sailing &#8211; Filicudi (sesta tappa)\" class=\"rev-slidebg tp-rs-img rs-lazyload\" data-lazyload=\"\/\/www.claudioamorese.it\/wp-content\/plugins\/revslider\/public\/assets\/assets\/transparent.png\" data-no-retina>\n<!--\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-15-slide-74-layer-4\" \n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:200px;y:-72px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:500px;h:375px;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"sp:90;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;sp:90;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:5;\"\n\t\t\t\t\t\t\t><img loading=\"lazy\" decoding=\"async\" src=\"\/\/www.claudioamorese.it\/wp-content\/plugins\/revslider\/public\/assets\/assets\/dummy.png\" class=\"tp-rs-img rs-lazyload\" width=\"2560\" height=\"1920\" data-lazyload=\"\/\/www.claudioamorese.it\/wp-content\/uploads\/2021\/08\/IMG_3349-scaled.jpg\" data-no-retina> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n-->\t\t\t\t\t\t<\/rs-slide>\n\t\t\t\t\t<\/rs-slides>\n\t\t\t\t<\/rs-module>\n\t\t\t\t<script type=\"text\/javascript\">\n\t\t\t\t\tsetREVStartSize({c: 'rev_slider_15_1',rl:[1240,1024,778,480],el:[200],gw:[1240],gh:[200],type:'standard',justify:'',layout:'fullwidth',mh:\"0\"});if (window.RS_MODULES!==undefined && window.RS_MODULES.modules!==undefined && window.RS_MODULES.modules[\"revslider151\"]!==undefined) {window.RS_MODULES.modules[\"revslider151\"].once = false;window.revapi15 = undefined;window.RS_MODULES.checkMinimal()}\n\t\t\t\t<\/script>\n\t\t\t<\/rs-module-wrap>\n\t\t\t<!-- END REVOLUTION SLIDER -->\n\n<br \/>\n<p>Giunti a Filicudi, passiamo a nord per goderci lo spettacolo di punta Zotta, dello scoglio La Canna e Montenassari, la grotta del bue marino prima di giungere a Pecorini a mare, dove abbiamo prenotato un gavitello.<\/p>\n<!-- Quarto slider -->\n\n\t\t\t<!-- START Filicudi REVOLUTION SLIDER 6.5.5 --><p class=\"rs-p-wp-fix\"><\/p>\n\t\t\t<rs-module-wrap id=\"rev_slider_16_2_wrapper\" data-source=\"gallery\" style=\"visibility:hidden;background:transparent;padding:0;margin:0px auto;margin-top:0;margin-bottom:0;\">\n\t\t\t\t<rs-module id=\"rev_slider_16_2\" style=\"\" data-version=\"6.5.5\">\n\t\t\t\t\t<rs-slides>\n\t\t\t\t\t\t<rs-slide style=\"position: absolute;\" data-key=\"rs-75\" data-title=\"Slide\" data-duration=\"1500ms\" data-anim=\"ms:400;\" data-in=\"o:0;\" data-out=\"a:false;\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"\/\/www.claudioamorese.it\/wp-content\/plugins\/revslider\/public\/assets\/assets\/dummy.png\" alt=\"Slide\" title=\"Aeolian Sailing &#8211; Filicudi (sesta tappa)\" class=\"rev-slidebg tp-rs-img rs-lazyload\" data-lazyload=\"\/\/www.claudioamorese.it\/wp-content\/plugins\/revslider\/public\/assets\/assets\/transparent.png\" data-no-retina>\n<!--\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-16-slide-75-layer-8\" \n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:200px;y:-112px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:475px;h:356px;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:9;\"\n\t\t\t\t\t\t\t><img loading=\"lazy\" decoding=\"async\" src=\"\/\/www.claudioamorese.it\/wp-content\/plugins\/revslider\/public\/assets\/assets\/dummy.png\" class=\"tp-rs-img rs-lazyload\" width=\"2560\" height=\"1920\" data-lazyload=\"\/\/www.claudioamorese.it\/wp-content\/uploads\/2021\/08\/IMG_3352-scaled.jpg\" data-no-retina> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n-->\t\t\t\t\t\t<\/rs-slide>\n\t\t\t\t\t\t<rs-slide style=\"position: absolute;\" data-key=\"rs-76\" data-title=\"Slide\" data-duration=\"1500ms\" data-anim=\"ms:300;\" data-in=\"o:0;\" data-out=\"a:false;\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"\/\/www.claudioamorese.it\/wp-content\/plugins\/revslider\/public\/assets\/assets\/dummy.png\" alt=\"Slide\" title=\"Aeolian Sailing &#8211; Filicudi (sesta tappa)\" class=\"rev-slidebg tp-rs-img rs-lazyload\" data-lazyload=\"\/\/www.claudioamorese.it\/wp-content\/plugins\/revslider\/public\/assets\/assets\/transparent.png\" data-no-retina>\n<!--\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-16-slide-76-layer-4\" \n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:200px;y:-72px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:475px;h:633px;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"sp:90;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;sp:90;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:5;\"\n\t\t\t\t\t\t\t><img loading=\"lazy\" decoding=\"async\" src=\"\/\/www.claudioamorese.it\/wp-content\/plugins\/revslider\/public\/assets\/assets\/dummy.png\" class=\"tp-rs-img rs-lazyload\" width=\"1920\" height=\"2560\" data-lazyload=\"\/\/www.claudioamorese.it\/wp-content\/uploads\/2021\/08\/IMG_4656-scaled.jpg\" data-no-retina> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n-->\t\t\t\t\t\t<\/rs-slide>\n\t\t\t\t\t\t<rs-slide style=\"position: absolute;\" data-key=\"rs-77\" data-title=\"Slide\" data-duration=\"1500ms\" data-anim=\"ms:300;\" data-in=\"o:0;\" data-out=\"a:false;\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"\/\/www.claudioamorese.it\/wp-content\/plugins\/revslider\/public\/assets\/assets\/dummy.png\" alt=\"Slide\" title=\"Aeolian Sailing &#8211; Filicudi (sesta tappa)\" class=\"rev-slidebg tp-rs-img rs-lazyload\" data-lazyload=\"\/\/www.claudioamorese.it\/wp-content\/plugins\/revslider\/public\/assets\/assets\/transparent.png\" data-no-retina>\n<!--\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-16-slide-77-layer-4\" \n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:200px;y:-72px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:500px;h:375px;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"sp:90;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;sp:90;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:5;\"\n\t\t\t\t\t\t\t><img loading=\"lazy\" decoding=\"async\" src=\"\/\/www.claudioamorese.it\/wp-content\/plugins\/revslider\/public\/assets\/assets\/dummy.png\" class=\"tp-rs-img rs-lazyload\" width=\"1600\" height=\"1200\" data-lazyload=\"\/\/www.claudioamorese.it\/wp-content\/uploads\/2021\/08\/WhatsApp-Image-2021-08-26-at-16.33.58.jpeg\" data-no-retina> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n-->\t\t\t\t\t\t<\/rs-slide>\n\t\t\t\t\t\t<rs-slide style=\"position: absolute;\" data-key=\"rs-78\" data-title=\"Slide\" data-duration=\"1500ms\" data-anim=\"ms:300;\" data-in=\"o:0;\" data-out=\"a:false;\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"\/\/www.claudioamorese.it\/wp-content\/plugins\/revslider\/public\/assets\/assets\/dummy.png\" alt=\"Slide\" title=\"Aeolian Sailing &#8211; Filicudi (sesta tappa)\" class=\"rev-slidebg tp-rs-img rs-lazyload\" data-lazyload=\"\/\/www.claudioamorese.it\/wp-content\/plugins\/revslider\/public\/assets\/assets\/transparent.png\" data-no-retina>\n<!--\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-16-slide-78-layer-4\" \n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:200px;y:-243px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:500px;h:667px;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"sp:90;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;sp:90;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:5;\"\n\t\t\t\t\t\t\t><img loading=\"lazy\" decoding=\"async\" src=\"\/\/www.claudioamorese.it\/wp-content\/plugins\/revslider\/public\/assets\/assets\/dummy.png\" class=\"tp-rs-img rs-lazyload\" width=\"1200\" height=\"1600\" data-lazyload=\"\/\/www.claudioamorese.it\/wp-content\/uploads\/2021\/08\/WhatsApp-Image-2021-08-26-at-16.33.58-2.jpeg\" data-no-retina> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n-->\t\t\t\t\t\t<\/rs-slide>\n\t\t\t\t\t<\/rs-slides>\n\t\t\t\t<\/rs-module>\n\t\t\t\t<script type=\"text\/javascript\">\n\t\t\t\t\tsetREVStartSize({c: 'rev_slider_16_2',rl:[1240,1024,778,480],el:[200],gw:[1240],gh:[200],type:'standard',justify:'',layout:'fullwidth',mh:\"0\"});if (window.RS_MODULES!==undefined && window.RS_MODULES.modules!==undefined && window.RS_MODULES.modules[\"revslider162\"]!==undefined) {window.RS_MODULES.modules[\"revslider162\"].once = false;window.revapi16 = undefined;window.RS_MODULES.checkMinimal()}\n\t\t\t\t<\/script>\n\t\t\t<\/rs-module-wrap>\n\t\t\t<!-- END REVOLUTION SLIDER -->\n\n\n\n<p><!DOCTYPE html><br \/>\n<html lang=\"it\"><\/p>\n<style>\n\/* Player Lyte *\/\n.lyte-container {\n    max-width: 600px;\n    width: 100%;\n    margin: 1em auto;\n    text-align: center;\n}\n.lyte-wrapper, .lyte, .lyMe {\n    display: block !important;\n    margin: 0 auto !important;\n    width: 100% !important;\n    max-width: 100% !important;\n    height: auto !important;\n}\n<\/style>\n<p><body><\/p>\n<div class=\"lyte-container\">\n    <div class=\"lyte-wrapper fourthree\" title=\"WhatsApp Video 2021 08 26 at 16 34 05\" style=\"width:420px;max-width:100%;margin:5px;\"><div class=\"lyMe\" id=\"WYL_ulVjTJnNBQw\" itemprop=\"video\" itemscope itemtype=\"https:\/\/schema.org\/VideoObject\"><div><meta itemprop=\"thumbnailUrl\" content=\"https:\/\/i.ytimg.com\/vi\/ulVjTJnNBQw\/hqdefault.jpg\" \/><meta itemprop=\"embedURL\" content=\"https:\/\/www.youtube.com\/embed\/ulVjTJnNBQw\" \/><meta itemprop=\"duration\" content=\"PT25S\" \/><meta itemprop=\"uploadDate\" content=\"2021-08-28T09:58:10Z\" \/><\/div><div id=\"lyte_ulVjTJnNBQw\" data-src=\"https:\/\/i.ytimg.com\/vi\/ulVjTJnNBQw\/hqdefault.jpg\" class=\"pL\"><div class=\"tC\"><div class=\"tT\" itemprop=\"name\">WhatsApp Video 2021 08 26 at 16 34 05<\/div><\/div><button tabindex=\"0\" class=\"play\"><\/button><div class=\"ctrl\"><div class=\"Lctrl\"><\/div><div class=\"Rctrl\"><\/div><\/div><\/div><noscript><a href=\"https:\/\/youtu.be\/ulVjTJnNBQw\" rel=\"nofollow\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i.ytimg.com\/vi\/ulVjTJnNBQw\/0.jpg\" alt=\"WhatsApp Video 2021 08 26 at 16 34 05\" width=\"420\" height=\"295\" \/><br \/>Watch this video on YouTube<\/a><\/noscript><meta itemprop=\"description\" content=\"WhatsApp Video 2021 08 26 at 16 34 05\"><\/div><\/div><div class=\"lL\" style=\"max-width:100%;width:420px;margin:5px;\"><\/div>\n<\/div>\n<p>A Pecorini a mare, prendiamo il gavitello e scendiamo a terra per cenare e visitare questo vecchio borgo di pescatori. Ci delude un po&#8217; la sua trasformazione turistica in luogo &#8220;alternativo&#8221; invaso da un numero significativo di &#8220;radical chic&#8221;.<\/p>\n\n\t\t\t<!-- START Pecorini a mare REVOLUTION SLIDER 6.5.5 --><p class=\"rs-p-wp-fix\"><\/p>\n\t\t\t<rs-module-wrap id=\"rev_slider_17_3_wrapper\" data-source=\"gallery\" style=\"visibility:hidden;background:transparent;padding:0;margin:0px auto;margin-top:0;margin-bottom:0;\">\n\t\t\t\t<rs-module id=\"rev_slider_17_3\" style=\"\" data-version=\"6.5.5\">\n\t\t\t\t\t<rs-slides>\n\t\t\t\t\t\t<rs-slide style=\"position: absolute;\" data-key=\"rs-79\" data-title=\"Slide\" data-duration=\"1500ms\" data-anim=\"ms:400;\" data-in=\"o:0;\" data-out=\"a:false;\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"\/\/www.claudioamorese.it\/wp-content\/plugins\/revslider\/public\/assets\/assets\/dummy.png\" alt=\"Slide\" title=\"Aeolian Sailing &#8211; Filicudi (sesta tappa)\" class=\"rev-slidebg tp-rs-img rs-lazyload\" data-lazyload=\"\/\/www.claudioamorese.it\/wp-content\/plugins\/revslider\/public\/assets\/assets\/transparent.png\" data-no-retina>\n<!--\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-17-slide-79-layer-8\" \n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:200px;y:-112px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:500px;h:375px;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:9;\"\n\t\t\t\t\t\t\t><img loading=\"lazy\" decoding=\"async\" src=\"\/\/www.claudioamorese.it\/wp-content\/plugins\/revslider\/public\/assets\/assets\/dummy.png\" class=\"tp-rs-img rs-lazyload\" width=\"2560\" height=\"1920\" data-lazyload=\"\/\/www.claudioamorese.it\/wp-content\/uploads\/2021\/08\/IMG_4684-scaled.jpg\" data-no-retina> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n-->\t\t\t\t\t\t<\/rs-slide>\n\t\t\t\t\t\t<rs-slide style=\"position: absolute;\" data-key=\"rs-80\" data-title=\"Slide\" data-duration=\"1500ms\" data-anim=\"ms:300;\" data-in=\"o:0;\" data-out=\"a:false;\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"\/\/www.claudioamorese.it\/wp-content\/plugins\/revslider\/public\/assets\/assets\/dummy.png\" alt=\"Slide\" title=\"Aeolian Sailing &#8211; Filicudi (sesta tappa)\" class=\"rev-slidebg tp-rs-img rs-lazyload\" data-lazyload=\"\/\/www.claudioamorese.it\/wp-content\/plugins\/revslider\/public\/assets\/assets\/transparent.png\" data-no-retina>\n<!--\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-17-slide-80-layer-4\" \n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:200px;y:-72px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:500px;h:375px;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"sp:90;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;sp:90;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:5;\"\n\t\t\t\t\t\t\t><img loading=\"lazy\" decoding=\"async\" src=\"\/\/www.claudioamorese.it\/wp-content\/plugins\/revslider\/public\/assets\/assets\/dummy.png\" class=\"tp-rs-img rs-lazyload\" width=\"2560\" height=\"1920\" data-lazyload=\"\/\/www.claudioamorese.it\/wp-content\/uploads\/2021\/08\/IMG_4695-scaled.jpg\" data-no-retina> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n-->\t\t\t\t\t\t<\/rs-slide>\n\t\t\t\t\t\t<rs-slide style=\"position: absolute;\" data-key=\"rs-81\" data-title=\"Slide\" data-duration=\"1500ms\" data-anim=\"ms:300;\" data-in=\"o:0;\" data-out=\"a:false;\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"\/\/www.claudioamorese.it\/wp-content\/plugins\/revslider\/public\/assets\/assets\/dummy.png\" alt=\"Slide\" title=\"Aeolian Sailing &#8211; Filicudi (sesta tappa)\" class=\"rev-slidebg tp-rs-img rs-lazyload\" data-lazyload=\"\/\/www.claudioamorese.it\/wp-content\/plugins\/revslider\/public\/assets\/assets\/transparent.png\" data-no-retina>\n<!--\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-17-slide-81-layer-4\" \n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:200px;y:-72px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:500px;h:375px;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"sp:90;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;sp:90;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:5;\"\n\t\t\t\t\t\t\t><img loading=\"lazy\" decoding=\"async\" src=\"\/\/www.claudioamorese.it\/wp-content\/plugins\/revslider\/public\/assets\/assets\/dummy.png\" class=\"tp-rs-img rs-lazyload\" width=\"2560\" height=\"1920\" data-lazyload=\"\/\/www.claudioamorese.it\/wp-content\/uploads\/2021\/08\/IMG_4685-1-scaled.jpg\" data-no-retina> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n-->\t\t\t\t\t\t<\/rs-slide>\n\t\t\t\t\t\t<rs-slide style=\"position: absolute;\" data-key=\"rs-82\" data-title=\"Slide\" data-duration=\"1500ms\" data-anim=\"ms:300;\" data-in=\"o:0;\" data-out=\"a:false;\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"\/\/www.claudioamorese.it\/wp-content\/plugins\/revslider\/public\/assets\/assets\/dummy.png\" alt=\"Slide\" title=\"Aeolian Sailing &#8211; Filicudi (sesta tappa)\" class=\"rev-slidebg tp-rs-img rs-lazyload\" data-lazyload=\"\/\/www.claudioamorese.it\/wp-content\/plugins\/revslider\/public\/assets\/assets\/transparent.png\" data-no-retina>\n<!--\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-17-slide-82-layer-4\" \n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:200px;y:-72px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:500px;h:375px;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"sp:90;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;sp:90;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:5;\"\n\t\t\t\t\t\t\t><img loading=\"lazy\" decoding=\"async\" src=\"\/\/www.claudioamorese.it\/wp-content\/plugins\/revslider\/public\/assets\/assets\/dummy.png\" class=\"tp-rs-img rs-lazyload\" width=\"2560\" height=\"1920\" data-lazyload=\"\/\/www.claudioamorese.it\/wp-content\/uploads\/2021\/08\/IMG_4670-2-scaled.jpg\" data-no-retina> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n-->\t\t\t\t\t\t<\/rs-slide>\n\t\t\t\t\t\t<rs-slide style=\"position: absolute;\" data-key=\"rs-83\" data-title=\"Slide\" data-duration=\"1500ms\" data-anim=\"ms:300;\" data-in=\"o:0;\" data-out=\"a:false;\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"\/\/www.claudioamorese.it\/wp-content\/plugins\/revslider\/public\/assets\/assets\/dummy.png\" alt=\"Slide\" title=\"Aeolian Sailing &#8211; Filicudi (sesta tappa)\" class=\"rev-slidebg tp-rs-img rs-lazyload\" data-lazyload=\"\/\/www.claudioamorese.it\/wp-content\/plugins\/revslider\/public\/assets\/assets\/transparent.png\" data-no-retina>\n<!--\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-17-slide-83-layer-4\" \n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:200px;y:-72px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:500px;h:375px;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"sp:90;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;sp:90;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:5;\"\n\t\t\t\t\t\t\t><img loading=\"lazy\" decoding=\"async\" src=\"\/\/www.claudioamorese.it\/wp-content\/plugins\/revslider\/public\/assets\/assets\/dummy.png\" class=\"tp-rs-img rs-lazyload\" width=\"2560\" height=\"1920\" data-lazyload=\"\/\/www.claudioamorese.it\/wp-content\/uploads\/2021\/08\/IMG_4688-1-scaled.jpg\" data-no-retina> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n-->\t\t\t\t\t\t<\/rs-slide>\n\t\t\t\t\t<\/rs-slides>\n\t\t\t\t<\/rs-module>\n\t\t\t\t<script type=\"text\/javascript\">\n\t\t\t\t\tsetREVStartSize({c: 'rev_slider_17_3',rl:[1240,1024,778,480],el:[200],gw:[1240],gh:[200],type:'standard',justify:'',layout:'fullwidth',mh:\"0\"});if (window.RS_MODULES!==undefined && window.RS_MODULES.modules!==undefined && window.RS_MODULES.modules[\"revslider173\"]!==undefined) {window.RS_MODULES.modules[\"revslider173\"].once = false;window.revapi17 = undefined;window.RS_MODULES.checkMinimal()}\n\t\t\t\t<\/script>\n\t\t\t<\/rs-module-wrap>\n\t\t\t<!-- END REVOLUTION SLIDER -->\n\n<p><\/p>\n<p>\n<a href=\"https:\/\/www.claudioamorese.it\/aeolian-sailing-il-prologo\/\">Vai al prologo<\/a> &#8211;<br \/>\n<a href=\"https:\/\/www.claudioamorese.it\/aeolian-sailing-lipari-1a-tappa\/\">Vai alla prima tappa<\/a> &#8211;<br \/>\n<a href=\"https:\/\/www.claudioamorese.it\/aeolian-sailing-salina-2a-tappa\/\">Vai alla seconda tappa<\/a> &#8211;<br \/>\n<a href=\"https:\/\/www.claudioamorese.it\/aeolian-sailing-panarea-3a-tappa\/\">Vai alla terza tappa<\/a> &#8211;<br \/>\n<a href=\"https:\/\/www.claudioamorese.it\/aeolian-sailing-vulcano-4a-tappa\/\">Vai alla quarta tappa<\/a> &#8211;<br \/>\n<a href=\"https:\/\/www.claudioamorese.it\/aeolian-sailing-stromboli-5a-tappa\/\">Vai alla quinta tappa<\/a> &#8211;<br \/>\n<a href=\"https:\/\/www.claudioamorese.it\/aeolian-sailing-il-ritorno\/\">Vai al ritorno<\/a>\n<\/p>\n<p><\/body><br \/>\n<\/html><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La sesta tappa: Filicudi Lentamente ci spostiamo verso Ovest per ridurre il tratto finale di ritorno a Termini Imerese. Giriamo intorno a Strombolicchio prima di fare rotta verso Filicudi Strombolicchio \u00e8 un neck, ossia una spina vulcanica, costituita dal magma solidificato di un vulcano di 200.000 anni fa ormai non pi\u00f9 esistente. Giunti a Filicudi, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"content-type":"","footnotes":""},"categories":[28],"tags":[94,95,93,92],"class_list":["post-2480","post","type-post","status-publish","format-standard","hentry","category-travels","tag-adventure","tag-avventura","tag-travels","tag-viaggi"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Aeolian Sailing - Filicudi (sesta tappa) - Claudio Amorese<\/title>\n<meta name=\"description\" content=\"Una settimana alle Eolie. Sesta tappa: FIlicudi.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.claudioamorese.it\/en\/aeolian-sailing-filicudi-6a-tappa\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Filicudi: L&#039;isola radical chic.\" \/>\n<meta property=\"og:description\" content=\"Una settimana alle Eolie. Sesta tappa: FIlicudi.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.claudioamorese.it\/en\/aeolian-sailing-filicudi-6a-tappa\/\" \/>\n<meta property=\"og:site_name\" content=\"Claudio Amorese\" \/>\n<meta property=\"article:published_time\" content=\"2021-08-28T10:15:16+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-11T20:36:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.claudioamorese.it\/wp-content\/uploads\/2021\/08\/IMG_4685-1-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1920\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Claudio Amorese\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Filicudi: L&#039;isola radical chic.\" \/>\n<meta name=\"twitter:description\" content=\"Una settimana alle Eolie. Sesta tappa: FIlicudi.\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/www.claudioamorese.it\/wp-content\/uploads\/2021\/08\/IMG_4685-1-scaled.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Claudio Amorese\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.claudioamorese.it\\\/aeolian-sailing-filicudi-6a-tappa\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.claudioamorese.it\\\/aeolian-sailing-filicudi-6a-tappa\\\/\"},\"author\":{\"name\":\"Claudio Amorese\",\"@id\":\"https:\\\/\\\/www.claudioamorese.it\\\/#\\\/schema\\\/person\\\/ed322e7a6de1cb5c4a26dde9a8afb2f1\"},\"headline\":\"Aeolian Sailing &#8211; Filicudi (sesta tappa)\",\"datePublished\":\"2021-08-28T10:15:16+00:00\",\"dateModified\":\"2025-12-11T20:36:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.claudioamorese.it\\\/aeolian-sailing-filicudi-6a-tappa\\\/\"},\"wordCount\":179,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.claudioamorese.it\\\/#\\\/schema\\\/person\\\/ed322e7a6de1cb5c4a26dde9a8afb2f1\"},\"image\":{\"@id\":\"https:\\\/\\\/www.claudioamorese.it\\\/aeolian-sailing-filicudi-6a-tappa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.claudioamorese.it\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/Immagine-2021-08-28-112720-e1630142956988-300x132.png\",\"keywords\":[\"adventure\",\"avventura\",\"travels\",\"Viaggi\"],\"articleSection\":[\"Travels\"],\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.claudioamorese.it\\\/aeolian-sailing-filicudi-6a-tappa\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.claudioamorese.it\\\/aeolian-sailing-filicudi-6a-tappa\\\/\",\"url\":\"https:\\\/\\\/www.claudioamorese.it\\\/aeolian-sailing-filicudi-6a-tappa\\\/\",\"name\":\"Aeolian Sailing - Filicudi (sesta tappa) - Claudio Amorese\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.claudioamorese.it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.claudioamorese.it\\\/aeolian-sailing-filicudi-6a-tappa\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.claudioamorese.it\\\/aeolian-sailing-filicudi-6a-tappa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.claudioamorese.it\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/Immagine-2021-08-28-112720-e1630142956988-300x132.png\",\"datePublished\":\"2021-08-28T10:15:16+00:00\",\"dateModified\":\"2025-12-11T20:36:11+00:00\",\"description\":\"Una settimana alle Eolie. Sesta tappa: FIlicudi.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.claudioamorese.it\\\/aeolian-sailing-filicudi-6a-tappa\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.claudioamorese.it\\\/aeolian-sailing-filicudi-6a-tappa\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/www.claudioamorese.it\\\/aeolian-sailing-filicudi-6a-tappa\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.claudioamorese.it\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/Immagine-2021-08-28-112720-e1630142956988-300x132.png\",\"contentUrl\":\"https:\\\/\\\/www.claudioamorese.it\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/Immagine-2021-08-28-112720-e1630142956988-300x132.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.claudioamorese.it\\\/aeolian-sailing-filicudi-6a-tappa\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.claudioamorese.it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Aeolian Sailing &#8211; Filicudi (sesta tappa)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.claudioamorese.it\\\/#website\",\"url\":\"https:\\\/\\\/www.claudioamorese.it\\\/\",\"name\":\"Claudio Amorese\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.claudioamorese.it\\\/#\\\/schema\\\/person\\\/ed322e7a6de1cb5c4a26dde9a8afb2f1\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.claudioamorese.it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/www.claudioamorese.it\\\/#\\\/schema\\\/person\\\/ed322e7a6de1cb5c4a26dde9a8afb2f1\",\"name\":\"Claudio Amorese\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/www.claudioamorese.it\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/IMG_1541-1-2.jpg\",\"url\":\"https:\\\/\\\/www.claudioamorese.it\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/IMG_1541-1-2.jpg\",\"contentUrl\":\"https:\\\/\\\/www.claudioamorese.it\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/IMG_1541-1-2.jpg\",\"width\":467,\"height\":700,\"caption\":\"Claudio Amorese\"},\"logo\":{\"@id\":\"https:\\\/\\\/www.claudioamorese.it\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/IMG_1541-1-2.jpg\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Aeolian Sailing - Filicudi (sesta tappa) - Claudio Amorese","description":"Una settimana alle Eolie. Sesta tappa: FIlicudi.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.claudioamorese.it\/en\/aeolian-sailing-filicudi-6a-tappa\/","og_locale":"en_GB","og_type":"article","og_title":"Filicudi: L'isola radical chic.","og_description":"Una settimana alle Eolie. Sesta tappa: FIlicudi.","og_url":"https:\/\/www.claudioamorese.it\/en\/aeolian-sailing-filicudi-6a-tappa\/","og_site_name":"Claudio Amorese","article_published_time":"2021-08-28T10:15:16+00:00","article_modified_time":"2025-12-11T20:36:11+00:00","og_image":[{"width":2560,"height":1920,"url":"https:\/\/www.claudioamorese.it\/wp-content\/uploads\/2021\/08\/IMG_4685-1-scaled.jpg","type":"image\/jpeg"}],"author":"Claudio Amorese","twitter_card":"summary_large_image","twitter_title":"Filicudi: L'isola radical chic.","twitter_description":"Una settimana alle Eolie. Sesta tappa: FIlicudi.","twitter_image":"https:\/\/www.claudioamorese.it\/wp-content\/uploads\/2021\/08\/IMG_4685-1-scaled.jpg","twitter_misc":{"Written by":"Claudio Amorese","Estimated reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.claudioamorese.it\/aeolian-sailing-filicudi-6a-tappa\/#article","isPartOf":{"@id":"https:\/\/www.claudioamorese.it\/aeolian-sailing-filicudi-6a-tappa\/"},"author":{"name":"Claudio Amorese","@id":"https:\/\/www.claudioamorese.it\/#\/schema\/person\/ed322e7a6de1cb5c4a26dde9a8afb2f1"},"headline":"Aeolian Sailing &#8211; Filicudi (sesta tappa)","datePublished":"2021-08-28T10:15:16+00:00","dateModified":"2025-12-11T20:36:11+00:00","mainEntityOfPage":{"@id":"https:\/\/www.claudioamorese.it\/aeolian-sailing-filicudi-6a-tappa\/"},"wordCount":179,"commentCount":0,"publisher":{"@id":"https:\/\/www.claudioamorese.it\/#\/schema\/person\/ed322e7a6de1cb5c4a26dde9a8afb2f1"},"image":{"@id":"https:\/\/www.claudioamorese.it\/aeolian-sailing-filicudi-6a-tappa\/#primaryimage"},"thumbnailUrl":"https:\/\/www.claudioamorese.it\/wp-content\/uploads\/2021\/08\/Immagine-2021-08-28-112720-e1630142956988-300x132.png","keywords":["adventure","avventura","travels","Viaggi"],"articleSection":["Travels"],"inLanguage":"en-GB","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.claudioamorese.it\/aeolian-sailing-filicudi-6a-tappa\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.claudioamorese.it\/aeolian-sailing-filicudi-6a-tappa\/","url":"https:\/\/www.claudioamorese.it\/aeolian-sailing-filicudi-6a-tappa\/","name":"Aeolian Sailing - Filicudi (sesta tappa) - Claudio Amorese","isPartOf":{"@id":"https:\/\/www.claudioamorese.it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.claudioamorese.it\/aeolian-sailing-filicudi-6a-tappa\/#primaryimage"},"image":{"@id":"https:\/\/www.claudioamorese.it\/aeolian-sailing-filicudi-6a-tappa\/#primaryimage"},"thumbnailUrl":"https:\/\/www.claudioamorese.it\/wp-content\/uploads\/2021\/08\/Immagine-2021-08-28-112720-e1630142956988-300x132.png","datePublished":"2021-08-28T10:15:16+00:00","dateModified":"2025-12-11T20:36:11+00:00","description":"Una settimana alle Eolie. Sesta tappa: FIlicudi.","breadcrumb":{"@id":"https:\/\/www.claudioamorese.it\/aeolian-sailing-filicudi-6a-tappa\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.claudioamorese.it\/aeolian-sailing-filicudi-6a-tappa\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.claudioamorese.it\/aeolian-sailing-filicudi-6a-tappa\/#primaryimage","url":"https:\/\/www.claudioamorese.it\/wp-content\/uploads\/2021\/08\/Immagine-2021-08-28-112720-e1630142956988-300x132.png","contentUrl":"https:\/\/www.claudioamorese.it\/wp-content\/uploads\/2021\/08\/Immagine-2021-08-28-112720-e1630142956988-300x132.png"},{"@type":"BreadcrumbList","@id":"https:\/\/www.claudioamorese.it\/aeolian-sailing-filicudi-6a-tappa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.claudioamorese.it\/"},{"@type":"ListItem","position":2,"name":"Aeolian Sailing &#8211; Filicudi (sesta tappa)"}]},{"@type":"WebSite","@id":"https:\/\/www.claudioamorese.it\/#website","url":"https:\/\/www.claudioamorese.it\/","name":"Claudio Amorese","description":"","publisher":{"@id":"https:\/\/www.claudioamorese.it\/#\/schema\/person\/ed322e7a6de1cb5c4a26dde9a8afb2f1"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.claudioamorese.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":["Person","Organization"],"@id":"https:\/\/www.claudioamorese.it\/#\/schema\/person\/ed322e7a6de1cb5c4a26dde9a8afb2f1","name":"Claudio Amorese","image":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.claudioamorese.it\/wp-content\/uploads\/2021\/08\/IMG_1541-1-2.jpg","url":"https:\/\/www.claudioamorese.it\/wp-content\/uploads\/2021\/08\/IMG_1541-1-2.jpg","contentUrl":"https:\/\/www.claudioamorese.it\/wp-content\/uploads\/2021\/08\/IMG_1541-1-2.jpg","width":467,"height":700,"caption":"Claudio Amorese"},"logo":{"@id":"https:\/\/www.claudioamorese.it\/wp-content\/uploads\/2021\/08\/IMG_1541-1-2.jpg"}}]}},"_links":{"self":[{"href":"https:\/\/www.claudioamorese.it\/en\/wp-json\/wp\/v2\/posts\/2480","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.claudioamorese.it\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.claudioamorese.it\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.claudioamorese.it\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.claudioamorese.it\/en\/wp-json\/wp\/v2\/comments?post=2480"}],"version-history":[{"count":54,"href":"https:\/\/www.claudioamorese.it\/en\/wp-json\/wp\/v2\/posts\/2480\/revisions"}],"predecessor-version":[{"id":3087,"href":"https:\/\/www.claudioamorese.it\/en\/wp-json\/wp\/v2\/posts\/2480\/revisions\/3087"}],"wp:attachment":[{"href":"https:\/\/www.claudioamorese.it\/en\/wp-json\/wp\/v2\/media?parent=2480"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.claudioamorese.it\/en\/wp-json\/wp\/v2\/categories?post=2480"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.claudioamorese.it\/en\/wp-json\/wp\/v2\/tags?post=2480"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}